{"id":910,"date":"2018-05-22T16:34:25","date_gmt":"2018-05-22T16:34:25","guid":{"rendered":"http:\/\/new.zuzukim.com\/?page_id=910"},"modified":"2020-01-31T09:46:55","modified_gmt":"2020-01-31T09:46:55","slug":"romanza","status":"publish","type":"page","link":"https:\/\/zuzukim.com\/dev\/romanza\/","title":{"rendered":"ROMANZA"},"content":{"rendered":"[vc_row css_animation=&#8221;fadeIn&#8221; animation=&#8221;fade-in&#8221; animation_delay=&#8221;2000&#8243; fullwidth=&#8221;yes&#8221; top_margin=&#8221;-45&#8243; bottom_margin=&#8221;-60&#8243; background_color=&#8221;#ffffff&#8221; css=&#8221;.vc_custom_1580463927052{padding-bottom: 30px !important;}&#8221;][vc_column][vc_single_image image=&#8221;3689&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; el_class=&#8221;couture_banner&#8221; css=&#8221;.vc_custom_1579162534969{margin-bottom: 20px !important;}&#8221;][vc_empty_space height=&#8221;30px&#8221;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;fadeIn&#8221; animation=&#8221;fade-in&#8221; animation_delay=&#8221;2000&#8243; top_margin=&#8221;0&#8243; bottom_margin=&#8221;0&#8243;][vc_column][vc_custom_heading text=&#8221;Romanza&#8221; font_container=&#8221;tag:h2|font_size:45px|text_align:center|color:%23000000|line_height:48px&#8221; google_fonts=&#8221;font_family:Meie%20Script%3Aregular|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;fadeIn&#8221; animation=&#8221;fade-in&#8221; animation_delay=&#8221;2000&#8243; top_margin=&#8221;0&#8243; bottom_margin=&#8221;0&#8243;][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;852&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-1-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;854&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-2-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;856&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-3-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;858&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-4-4\/&#8221;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;fadeIn&#8221; animation=&#8221;fade-in&#8221; animation_delay=&#8221;2000&#8243; top_margin=&#8221;0&#8243; bottom_margin=&#8221;0&#8243;][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;860&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-5-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;862&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-6-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;864&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-7-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;866&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-8-4\/&#8221;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;fadeIn&#8221; animation=&#8221;fade-in&#8221; animation_delay=&#8221;2000&#8243; top_margin=&#8221;0&#8243; bottom_margin=&#8221;0&#8243;][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;868&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-9-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;870&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-10-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;872&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-11-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;874&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-12-4\/&#8221;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;fadeIn&#8221; animation=&#8221;fade-in&#8221; animation_delay=&#8221;2000&#8243; top_margin=&#8221;0&#8243; bottom_margin=&#8221;0&#8243;][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;876&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-13-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;878&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-14-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;880&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-15-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row]","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=&#8221;fadeIn&#8221; animation=&#8221;fade-in&#8221; animation_delay=&#8221;2000&#8243; fullwidth=&#8221;yes&#8221; top_margin=&#8221;-45&#8243; bottom_margin=&#8221;-60&#8243; background_color=&#8221;#ffffff&#8221; css=&#8221;.vc_custom_1580463927052{padding-bottom: 30px !important;}&#8221;][vc_column][vc_single_image image=&#8221;3689&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; el_class=&#8221;couture_banner&#8221; css=&#8221;.vc_custom_1579162534969{margin-bottom: 20px !important;}&#8221;][vc_empty_space height=&#8221;30px&#8221;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;fadeIn&#8221; animation=&#8221;fade-in&#8221; animation_delay=&#8221;2000&#8243; top_margin=&#8221;0&#8243; bottom_margin=&#8221;0&#8243;][vc_column][vc_custom_heading text=&#8221;Romanza&#8221; font_container=&#8221;tag:h2|font_size:45px|text_align:center|color:%23000000|line_height:48px&#8221; google_fonts=&#8221;font_family:Meie%20Script%3Aregular|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;fadeIn&#8221; animation=&#8221;fade-in&#8221; animation_delay=&#8221;2000&#8243; top_margin=&#8221;0&#8243; bottom_margin=&#8221;0&#8243;][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;852&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-1-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;854&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-2-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;856&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.zuzukim.com\/portfolio\/look-3-4\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;858&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-910","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/zuzukim.com\/dev\/wp-json\/wp\/v2\/pages\/910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zuzukim.com\/dev\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zuzukim.com\/dev\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zuzukim.com\/dev\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/zuzukim.com\/dev\/wp-json\/wp\/v2\/comments?post=910"}],"version-history":[{"count":0,"href":"https:\/\/zuzukim.com\/dev\/wp-json\/wp\/v2\/pages\/910\/revisions"}],"wp:attachment":[{"href":"https:\/\/zuzukim.com\/dev\/wp-json\/wp\/v2\/media?parent=910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}